{"id":6091,"date":"2024-04-26T09:57:55","date_gmt":"2024-04-26T07:57:55","guid":{"rendered":"https:\/\/www.nicalia.com\/nicapedia\/guias\/cpanel\/restaurar-o-descargar-una-copia-completa-con-jetbackup-5\/"},"modified":"2025-08-27T17:18:09","modified_gmt":"2025-08-27T15:18:09","slug":"restaurar-o-descargar-una-copia-completa-con-jetbackup-5","status":"publish","type":"docs","link":"https:\/\/www.nicalia.com\/nicapedia\/restaurar-o-descargar-una-copia-completa-con-jetbackup-5\/","title":{"rendered":"Restaurar o descargar una copia completa con Jetbackup 5"},"content":{"rendered":"\n<p>En esta secci\u00f3n puedes ver, restaurar y descargar las copias de seguridad de tu cuenta o elegir restaurar elementos de copia de seguridad espec\u00edficos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"RestaurarodescargarunacopiacompletaconJetbackup5-Elementospararestaurar\/descargar\">Elementos para restaurar\/descargar<\/h3>\n\n\n\n<p>Cada elemento de respaldo tiene una pesta\u00f1a espec\u00edfica para Restaurar o Descargar. La pesta\u00f1a&nbsp;<strong>&#8220;Full backup&#8221;<\/strong>, de forma predeterminada, incluir\u00e1 todos los elementos de copia de seguridad.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cuenta completa&nbsp;<\/li>\n\n\n\n<li>Archivos del directorio de inicio<\/li>\n\n\n\n<li>Bases de datos&nbsp;<\/li>\n\n\n\n<li>Usuarios de la base de datos&nbsp;<\/li>\n\n\n\n<li>Cuentas de correo electr\u00f3nico<\/li>\n\n\n\n<li>Cuentas FTP<\/li>\n\n\n\n<li>Trabajos de cron<\/li>\n\n\n\n<li>Zonas DNS<\/li>\n\n\n\n<li>Certificados SSL<\/li>\n<\/ul>\n\n\n\n<p>Para restaurar\/descargar una copia completa deber\u00e1s seguir los siguientes pasos:<\/p>\n\n\n\n<p>1. Dir\u00edgete hacia tu cuenta <strong>cPanel <\/strong>&gt;&gt; <strong>Jetbackup 5.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"986\" height=\"254\" src=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952601.png\" alt=\"\" class=\"wp-image-7845\" srcset=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952601.png 986w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952601-300x77.png 300w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952601-768x198.png 768w\" sizes=\"(max-width: 986px) 100vw, 986px\" \/><\/figure>\n\n\n\n<p>2. Haz clic en&nbsp;<strong>&#8220;Full backups&#8221;.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"522\" src=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/05\/image-18-1024x522.png\" alt=\"\" class=\"wp-image-6826\" srcset=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/05\/image-18-1024x522.png 1024w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/05\/image-18-300x153.png 300w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/05\/image-18-768x392.png 768w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/05\/image-18.png 1453w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>3. Selecciona la fecha de la copia de seguridad a restaurar\/descargar y haz clic en&nbsp;<strong>&#8220;Restore&#8221;&nbsp;<\/strong>(restaurar) o&nbsp;<strong>&#8220;Download&#8221;&nbsp;<\/strong>(descargar).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"611\" src=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952372-1024x611.png\" alt=\"\" class=\"wp-image-7846\" srcset=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952372-1024x611.png 1024w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952372-300x179.png 300w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952372-768x458.png 768w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952372.png 1441w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"616\" src=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952373-1024x616.png\" alt=\"\" class=\"wp-image-7848\" srcset=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952373-1024x616.png 1024w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952373-300x180.png 300w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952373-768x462.png 768w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952373.png 1441w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>4. En la nueva ventana, haz clic en&nbsp;&#8220;Restore Selected Items&#8221;&nbsp;si has seleccionado&nbsp;&#8220;Restore&#8221;&nbsp;o &#8220;Download selected items&#8221;&nbsp;si has seleccionado&nbsp;&#8220;Download&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"489\" src=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952374-1024x489.png\" alt=\"\" class=\"wp-image-7849\" srcset=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952374-1024x489.png 1024w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952374-300x143.png 300w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952374-768x367.png 768w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952374.png 1194w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"450\" src=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952376-1024x450.png\" alt=\"\" class=\"wp-image-7850\" srcset=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952376-1024x450.png 1024w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952376-300x132.png 300w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952376-768x337.png 768w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952376.png 1195w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><img decoding=\"async\" width=\"1200\" src=\"https:\/\/wiki.nicalia.com\/download\/attachments\/24952369\/image2023-2-15_12-19-16.png?version=1&amp;modificationDate=1676459941870&amp;api=v2\" alt=\"\">Si no quieres perder los correos actuales, a la hora de restaurar una copia completa procura quitar de la restauraci\u00f3n (Remove items) el elemento &#8220;<strong>Email Accounts&#8221;.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Merge live account data with backup data<\/strong><br>Esta opci\u00f3n combinar\u00e1 tus datos de copia de seguridad con los datos existentes en tu cuenta. Los datos en vivo tienen prioridad sobre los datos de restauraci\u00f3n. Si no deseas preservar nada no marques esta opci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<pre class=\"wp-block-preformatted\"><strong>Nota<\/strong><br>Si no quieres perder los correos actuales, a la hora de restaurar una copia completa procura quitar de la restauraci\u00f3n (Remove items) el elemento \"<strong>Email Accounts\".<\/strong><br><br><strong>Merge live account data with backup data<\/strong><br>Esta opci\u00f3n combinar\u00e1 tus datos de copia de seguridad con los datos existentes en tu cuenta. Los datos en vivo tienen prioridad sobre los datos de restauraci\u00f3n. Si no deseas preservar nada no marques esta opci\u00f3n.<\/pre>\n\n\n\n<p>Una vez hayas hecho clic en&nbsp;<strong>&#8220;Restore Selected Items&#8221;<\/strong>&nbsp;o&nbsp;&#8220;<strong>Download selected items&#8221;&nbsp;<\/strong>se a\u00f1adir\u00e1 la tarea a la cola.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"368\" src=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952377-1024x368.png\" alt=\"\" class=\"wp-image-7851\" srcset=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952377-1024x368.png 1024w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952377-300x108.png 300w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952377-768x276.png 768w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952377.png 1454w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"329\" src=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952378-1024x329.png\" alt=\"\" class=\"wp-image-7852\" srcset=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952378-1024x329.png 1024w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952378-300x97.png 300w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952378-768x247.png 768w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952378.png 1439w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Una vez finalice, aparecer\u00e1 la tarea en la cola con el estado&nbsp;<strong>&#8220;Completado&#8221;&nbsp;<\/strong>(completed).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En esta secci\u00f3n puedes ver, restaurar y descargar las copias de seguridad de tu cuenta o elegir restaurar elementos de copia de seguridad espec\u00edficos. Elementos para restaurar\/descargar Cada elemento de respaldo tiene una pesta\u00f1a espec\u00edfica para Restaurar o Descargar. La pesta\u00f1a&nbsp;&#8220;Full backup&#8221;, de forma predeterminada, incluir\u00e1 todos los elementos de copia de seguridad. Para restaurar\/descargar [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":8634,"menu_order":19,"comment_status":"open","ping_status":"closed","template":"","doc_tag":[],"doc_badge":[],"class_list":["post-6091","docs","type-docs","status-publish","hentry","no-post-thumbnail"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/docs\/6091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/comments?post=6091"}],"version-history":[{"count":5,"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/docs\/6091\/revisions"}],"predecessor-version":[{"id":9453,"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/docs\/6091\/revisions\/9453"}],"up":[{"embeddable":true,"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/docs\/8634"}],"wp:attachment":[{"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/media?parent=6091"}],"wp:term":[{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/doc_tag?post=6091"},{"taxonomy":"doc_badge","embeddable":true,"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/doc_badge?post=6091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}