{"id":6216,"date":"2024-04-26T12:25:37","date_gmt":"2024-04-26T10:25:37","guid":{"rendered":"https:\/\/www.nicalia.com\/nicapedia\/guias\/cpanel\/configurar-el-idioma-de-cpanel\/"},"modified":"2025-08-27T17:18:08","modified_gmt":"2025-08-27T15:18:08","slug":"configurar-el-idioma-de-cpanel","status":"publish","type":"docs","link":"https:\/\/www.nicalia.com\/nicapedia\/configurar-el-idioma-de-cpanel\/","title":{"rendered":"Configurar el idioma de cPanel"},"content":{"rendered":"\n<p>Para cambiar el idioma de cPanel deber\u00e1s acceder a la cuenta y realizar los siguientes pasos :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Haz clic en el apartado superior derecho sobre el icono <img decoding=\"async\" height=\"34\" src=\"https:\/\/wiki.nicalia.com\/download\/thumbnails\/2981937\/5XxWFFhEo4.png?version=1&amp;modificationDate=1676892753004&amp;api=v2\" alt=\"\">para &#8220;Cambiar idioma&#8221; (depender\u00e1 del idioma que tenga establecido en ese momento la cuenta cPanel).<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"395\" src=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952486-1024x395.png\" alt=\"\" class=\"wp-image-8911\" srcset=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952486-1024x395.png 1024w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952486-300x116.png 300w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952486-768x296.png 768w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952486-1536x592.png 1536w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952486.png 1595w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Otra alternativa es irse al apartado <strong>Preferencias &gt;&gt; Cambiar idioma<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"983\" height=\"199\" src=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952485.png\" alt=\"\" class=\"wp-image-8913\" srcset=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952485.png 983w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952485-300x61.png 300w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952485-768x155.png 768w\" sizes=\"(max-width: 983px) 100vw, 983px\" \/><\/figure>\n\n\n\n<p>2. En el desplegable seleccionar el idioma que deseas.<\/p>\n\n\n\n<p>3. Haz clic en <strong>Change o Cambiar<\/strong> y ya tendr\u00e1s el idioma cambiado.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1024\" height=\"318\" src=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952489-1024x318.png\" alt=\"\" class=\"wp-image-8914\" srcset=\"https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952489-1024x318.png 1024w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952489-300x93.png 300w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952489-768x239.png 768w, https:\/\/www.nicalia.com\/nicapedia\/wp-content\/uploads\/2024\/06\/24952489.png 1336w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para cambiar el idioma de cPanel deber\u00e1s acceder a la cuenta y realizar los siguientes pasos : Otra alternativa es irse al apartado Preferencias &gt;&gt; Cambiar idioma. 2. En el desplegable seleccionar el idioma que deseas. 3. Haz clic en Change o Cambiar y ya tendr\u00e1s el idioma cambiado.<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":8636,"menu_order":2,"comment_status":"open","ping_status":"closed","template":"","doc_tag":[],"doc_badge":[],"class_list":["post-6216","docs","type-docs","status-publish","hentry","no-post-thumbnail"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/docs\/6216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/comments?post=6216"}],"version-history":[{"count":5,"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/docs\/6216\/revisions"}],"predecessor-version":[{"id":9438,"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/docs\/6216\/revisions\/9438"}],"up":[{"embeddable":true,"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/docs\/8636"}],"wp:attachment":[{"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/media?parent=6216"}],"wp:term":[{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/doc_tag?post=6216"},{"taxonomy":"doc_badge","embeddable":true,"href":"https:\/\/www.nicalia.com\/nicapedia\/wp-json\/wp\/v2\/doc_badge?post=6216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}